{"id":12,"count":3,"description":"","link":"https:\/\/example.websitemas.com\/saludblog\/tag\/breath\/","name":"Breath","slug":"breath","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/example.websitemas.com\/saludblog\/wp-json\/wp\/v2\/tags\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/example.websitemas.com\/saludblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/example.websitemas.com\/saludblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/example.websitemas.com\/saludblog\/wp-json\/wp\/v2\/posts?tags=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}