{"id":3,"count":6,"description":"","link":"https:\/\/example.websitemas.com\/saludblog\/category\/brain\/","name":"Cerebro","slug":"brain","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/example.websitemas.com\/saludblog\/wp-json\/wp\/v2\/categories\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/example.websitemas.com\/saludblog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/example.websitemas.com\/saludblog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/example.websitemas.com\/saludblog\/wp-json\/wp\/v2\/posts?categories=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}